{"id":2990,"date":"2022-03-25T10:55:13","date_gmt":"2022-03-25T09:55:13","guid":{"rendered":"http:\/\/building-drainage.com\/legal-notice\/"},"modified":"2022-03-31T12:05:52","modified_gmt":"2022-03-31T10:05:52","slug":"legal-notice","status":"publish","type":"page","link":"https:\/\/www.building-drainage.com\/de\/legal-notice\/","title":{"rendered":"Impressum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2990\" class=\"elementor elementor-2990 elementor-211\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e6dd64 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9e6dd64\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e24a0d\" data-id=\"3e24a0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a89f461 elementor-widget elementor-widget-template\" data-id=\"a89f461\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"1397\" class=\"elementor elementor-1397\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-20591e5 e-flex e-con-boxed e-con e-parent\" data-id=\"20591e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48dc1f2 elementor-widget elementor-widget-template\" data-id=\"48dc1f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"345\" class=\"elementor elementor-345\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2ec7e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2ec7e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c240f21\" data-id=\"c240f21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4b8cd5 elementor-align-center elementor-widget elementor-widget-breadcrumbs\" data-id=\"a4b8cd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.building-drainage.com\/de\/\">Startseite<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-814872a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"814872a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72fcce9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72fcce9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c74b1f\" data-id=\"9c74b1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-862efbd elementor-widget elementor-widget-heading\" data-id=\"862efbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Impressum<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f5e43e elementor-widget elementor-widget-heading\" data-id=\"2f5e43e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Impressum - Preis GmbH<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d719b2 elementor-widget elementor-widget-text-editor\" data-id=\"6d719b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Preis GmbH <\/strong><br>\nA-2763 Pernitz, Josef Nitsch Str. 5<\/p>\n<p>Tel. <a href=\"tel:+432632733 550\">+43 (0)2632\/733 55-0<\/a><br>\nEmail: <a href=\"mailto:office.austria@preisgroup.com\">office.austria@preisgroup.com<br>\n<\/a><\/p>\n<p><strong>UID Nummer:<\/strong> ATU 45466204<\/p>\n<p><strong>Firmenbuchnummer:<\/strong> FN 169954h<br>\n<strong>Firmenbuchgericht:<\/strong> Landesgericht Wiener Neustadt&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec0176e elementor-widget elementor-widget-heading\" data-id=\"ec0176e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Urheberrecht<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66cc4dd elementor-widget elementor-widget-text-editor\" data-id=\"66cc4dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Der Inhalt dieser Website ist urheberrechtlich gesch\u00fctzt. Alle Rechte, auch die der \u00dcbersetzung, des Nachdrucks und der Vervielf\u00e4ltigung des Inhalts oder Teilen daraus, behalten wir uns vor. Ohne schriftliche Genehmigung der Preis GmbH., darf der Inhalt dieser Seite in keiner Form reproduziert oder unter Verwendung elektronischer Systeme verarbeitet, vervielf\u00e4ltigt oder verbreitet werden. Ausgenommen davon ist \u2013 vorausgesetzt es wird keine \u00c4nderung am Inhalt der Website vorgenommen \u2013 die Verwendung des Inhalts zu rein pers\u00f6nlichen und nicht- kommerziellen Zwecken. Diese Erlaubnis endet, wenn gegen die oben genannten Bedingungen versto\u00dfen wird.<\/p><p>S\u00e4mtliche Bilder, Animationen und Filme von Maschinen, Anlagen oder Produkten sind Eigentum der Preis GmbH. Das Herunterladen auf die Festplatte Ihres Rechners ist ausschlie\u00dflich zu privaten Zwecken gestattet. Eine kommerzielle Verwendung bedarf einer schriftlichen Genehmigung.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a462de1 elementor-widget elementor-widget-heading\" data-id=\"a462de1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Haftungsausschluss<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9123b1e elementor-widget elementor-widget-text-editor\" data-id=\"9123b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Obwohl bei der Zusammenstellung der auf unseren Webseiten enthaltenen Informationen gr\u00f6\u00dfte Sorgfalt angewandt wurde, kann Preis GmbH. nicht f\u00fcr deren Korrektheit garantieren und geht damit keinerlei Verpflichtungen ein. In keinem Fall kann Preis GmbH f\u00fcr etwaige Sch\u00e4den irgendwelcher Art verantwortlich gemacht werden, die durch die Benutzung oder im Zusammenhang mit der Benutzung der hier bereitgestellten Informationen entstehen, seien es direkte oder indirekte Sch\u00e4den, Folgesch\u00e4den oder Sondersch\u00e4den einschlie\u00dflich entgangenen Gewinns, oder Sch\u00e4den, die aus dem Verlust von Daten entstehen.<\/p><p>Wir behalten uns \u00c4nderungen der Informationen auf dieser Website, die wir unverbindlich zur Verf\u00fcgung stellen, jederzeit und ohne vorherige Ank\u00fcndigung vor.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0159f50 elementor-widget elementor-widget-heading\" data-id=\"0159f50\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Google Analytics<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e9d69c elementor-widget elementor-widget-text-editor\" data-id=\"8e9d69c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Diese Website benutzt Google Analytics, einen Webanalysedienst der Google Inc. (\u201eGoogle\u201d). Google Analytics verwendet sog. \u201eCookies\u201d, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glicht. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung diese Website (einschlie\u00dflich Ihrer IP-Adresse) wird an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Google wird diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten f\u00fcr die Websitebetreiber zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen zu erbringen. Auch wird Google diese Informationen gegebenenfalls an Dritte \u00fcbertragen, sofern dies gesetzlich vorgeschrieben oder soweit Dritte diese Daten im Auftrag von Google verarbeiten. Google wird in keinem Fall Ihre IP-Adresse mit anderen Daten der Google in Verbindung bringen. Sie k\u00f6nnen die Installation der Cookies durch eine entsprechende Einstellung Ihrer Browser Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website voll umf\u00e4nglich nutzen k\u00f6nnen. Durch die Nutzung dieser Website erkl\u00e4ren Sie sich mit der Bearbeitung der \u00fcber Sie erhobenen Daten durch Google in der zuvor beschriebenen Art und Weise und zu dem zuvor benannten Zweck einverstanden.<\/p><p>Falls Sie ihren Besuch auf unserer Seite nicht von Google Analytics auswerten lassen wollen, k\u00f6nnen Sie das Deaktivierungs-Add-on f\u00fcr Browser von Google Analytics (\/BETA) nutzen. Laut Google teilt dieses Add-on dem JavaScript (\/ga.js) von Google Analytics mit, dass keine Informationen \u00fcber den Website-Besuch an Google Analytics \u00fcbermittelt werden sollen.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Impressum Impressum &#8211; Preis GmbH Preis GmbH A-2763 Pernitz, Josef Nitsch Str. 5 Tel. +43 (0)2632\/733 55-0 Email: office.austria@preisgroup.com UID Nummer: ATU 45466204 Firmenbuchnummer: FN 169954h Firmenbuchgericht: Landesgericht Wiener Neustadt&nbsp; Urheberrecht Der Inhalt dieser Website ist urheberrechtlich gesch\u00fctzt. Alle Rechte, auch die der \u00dcbersetzung, des Nachdrucks und der Vervielf\u00e4ltigung des Inhalts oder Teilen daraus, behalten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":280,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2990","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impressum - PREIS Group Drainage Systems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.building-drainage.com\/de\/legal-notice\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impressum - PREIS Group Drainage Systems\" \/>\n<meta property=\"og:description\" content=\"Impressum Impressum &#8211; Preis GmbH Preis GmbH A-2763 Pernitz, Josef Nitsch Str. 5 Tel. +43 (0)2632\/733 55-0 Email: office.austria@preisgroup.com UID Nummer: ATU 45466204 Firmenbuchnummer: FN 169954h Firmenbuchgericht: Landesgericht Wiener Neustadt&nbsp; Urheberrecht Der Inhalt dieser Website ist urheberrechtlich gesch\u00fctzt. Alle Rechte, auch die der \u00dcbersetzung, des Nachdrucks und der Vervielf\u00e4ltigung des Inhalts oder Teilen daraus, behalten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.building-drainage.com\/de\/legal-notice\/\" \/>\n<meta property=\"og:site_name\" content=\"PREIS Group Drainage Systems\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-31T10:05:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/legal-notice\\\/\",\"url\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/legal-notice\\\/\",\"name\":\"Impressum - PREIS Group Drainage Systems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/#website\"},\"datePublished\":\"2022-03-25T09:55:13+00:00\",\"dateModified\":\"2022-03-31T10:05:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/legal-notice\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/legal-notice\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/legal-notice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impressum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/\",\"name\":\"PREIS Group Drainage Systems\",\"description\":\"Cast iron Drainage by professionals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/#organization\",\"name\":\"PREIS Group Drainage Systems\",\"url\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.building-drainage.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/preis-ds-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.building-drainage.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/preis-ds-logo.png\",\"width\":500,\"height\":127,\"caption\":\"PREIS Group Drainage Systems\"},\"image\":{\"@id\":\"https:\\\/\\\/www.building-drainage.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impressum - PREIS Group Drainage Systems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.building-drainage.com\/de\/legal-notice\/","og_locale":"de_DE","og_type":"article","og_title":"Impressum - PREIS Group Drainage Systems","og_description":"Impressum Impressum &#8211; Preis GmbH Preis GmbH A-2763 Pernitz, Josef Nitsch Str. 5 Tel. +43 (0)2632\/733 55-0 Email: office.austria@preisgroup.com UID Nummer: ATU 45466204 Firmenbuchnummer: FN 169954h Firmenbuchgericht: Landesgericht Wiener Neustadt&nbsp; Urheberrecht Der Inhalt dieser Website ist urheberrechtlich gesch\u00fctzt. Alle Rechte, auch die der \u00dcbersetzung, des Nachdrucks und der Vervielf\u00e4ltigung des Inhalts oder Teilen daraus, behalten [&hellip;]","og_url":"https:\/\/www.building-drainage.com\/de\/legal-notice\/","og_site_name":"PREIS Group Drainage Systems","article_modified_time":"2022-03-31T10:05:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.building-drainage.com\/de\/legal-notice\/","url":"https:\/\/www.building-drainage.com\/de\/legal-notice\/","name":"Impressum - PREIS Group Drainage Systems","isPartOf":{"@id":"https:\/\/www.building-drainage.com\/de\/#website"},"datePublished":"2022-03-25T09:55:13+00:00","dateModified":"2022-03-31T10:05:52+00:00","breadcrumb":{"@id":"https:\/\/www.building-drainage.com\/de\/legal-notice\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.building-drainage.com\/de\/legal-notice\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.building-drainage.com\/de\/legal-notice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.building-drainage.com\/de\/"},{"@type":"ListItem","position":2,"name":"Impressum"}]},{"@type":"WebSite","@id":"https:\/\/www.building-drainage.com\/de\/#website","url":"https:\/\/www.building-drainage.com\/de\/","name":"PREIS Group Drainage Systems","description":"Cast iron Drainage by professionals","publisher":{"@id":"https:\/\/www.building-drainage.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.building-drainage.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.building-drainage.com\/de\/#organization","name":"PREIS Group Drainage Systems","url":"https:\/\/www.building-drainage.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.building-drainage.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.building-drainage.com\/wp-content\/uploads\/2021\/09\/preis-ds-logo.png","contentUrl":"https:\/\/www.building-drainage.com\/wp-content\/uploads\/2021\/09\/preis-ds-logo.png","width":500,"height":127,"caption":"PREIS Group Drainage Systems"},"image":{"@id":"https:\/\/www.building-drainage.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.building-drainage.com\/de\/wp-json\/wp\/v2\/pages\/2990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.building-drainage.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.building-drainage.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.building-drainage.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.building-drainage.com\/de\/wp-json\/wp\/v2\/comments?post=2990"}],"version-history":[{"count":0,"href":"https:\/\/www.building-drainage.com\/de\/wp-json\/wp\/v2\/pages\/2990\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.building-drainage.com\/de\/wp-json\/wp\/v2\/media?parent=2990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}